{"id":87588,"date":"2024-11-05T08:19:23","date_gmt":"2024-11-05T08:19:23","guid":{"rendered":"https:\/\/www.expondo.co.uk\/inspirations\/obstbaeume-beschneiden\/"},"modified":"2024-11-05T08:20:53","modified_gmt":"2024-11-05T08:20:53","slug":"tailler-les-arbres-fruitiers","status":"publish","type":"post","link":"https:\/\/www.expondo.fr\/inspirations\/tailler-les-arbres-fruitiers\/","title":{"rendered":"Tailler les arbres fruitiers\u00a0: conseils pour des r\u00e9coltes abondantes tous les ans"},"content":{"rendered":"\n<p><strong>Vous voulez planter des arbres fruitiers sur votre terrain<\/strong>&nbsp;<strong>? Dans ce cas, pr\u00e9parez-vous \u00e0 beaucoup de travail chaque ann\u00e9e. Au printemps, vos arbres seront couverts de fleurs qui donneront de d\u00e9licieux fruits en automne. L&#8217;une des t\u00e2ches consiste \u00e0 tailler les arbres. Mais quel est le bon moment pour le faire et comment s&#8217;y prendre ?<\/strong><\/p>\n\n\n<div class=\"wp-block-ub-table-of-contents-block ub_table-of-contents\" data-showtext=\"show\" data-hidetext=\"hide\" data-scrolltype=\"auto\" id=\"ub_table-of-contents-7b368d45-7e98-44b0-b677-4fb18fafac3a\" data-initiallyhideonmobile=\"false\"\n                    data-initiallyshow=\"true\"><div class=\"ub_table-of-contents-header-container\"><div class=\"ub_table-of-contents-header\">\n                    <div class=\"ub_table-of-contents-title\"><\/div><\/div><\/div><div class=\"ub_table-of-contents-extra-container\"><div class=\"ub_table-of-contents-container ub_table-of-contents-1-column \"><ul><li><a href=https:\/\/www.expondo.fr\/inspirations\/tailler-les-arbres-fruitiers\/#0-pourquoi-tailler-les-arbres-fruitiers->Pourquoi tailler les arbres fruitiers&nbsp;?<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/tailler-les-arbres-fruitiers\/#1-quand-tailler-les-arbres-fruitiers->Quand tailler les arbres fruitiers&nbsp;?<\/a><ul><li><a href=https:\/\/www.expondo.fr\/inspirations\/tailler-les-arbres-fruitiers\/#2-quel-est-le-meilleur-moment-pour-tailler-les-pommiers->Quel est le meilleur moment pour tailler les pommiers&nbsp;?<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/tailler-les-arbres-fruitiers\/#3-taillez-les-poiriers-comme-les-pommiers>Taillez les poiriers comme les pommiers<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/tailler-les-arbres-fruitiers\/#4-le-bon-moment-pour-tailler-les-p%C3%AAchers-et-les-abricotiers>Le bon moment pour tailler les p\u00eachers et les abricotiers<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/tailler-les-arbres-fruitiers\/#5-taille-dentretien-des-cerisiers-en-%C3%A9t%C3%A9>Taille d&#8217;entretien des cerisiers en \u00e9t\u00e9<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/tailler-les-arbres-fruitiers\/#6-quand-tailler-un-prunier->Quand tailler un prunier&nbsp;?<\/a><\/li><\/ul><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/tailler-les-arbres-fruitiers\/#7-comment-tailler-les-arbres-fruitiers->Comment tailler les arbres fruitiers&nbsp;?<\/a><ul><li><a href=https:\/\/www.expondo.fr\/inspirations\/tailler-les-arbres-fruitiers\/#8-taille-de-rajeunissement>Taille de rajeunissement<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/tailler-les-arbres-fruitiers\/#9-taille-de-formation>Taille de formation<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/tailler-les-arbres-fruitiers\/#10-taille-sanitaire-et-taille-dentretien>Taille sanitaire et taille d&#8217;entretien<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/tailler-les-arbres-fruitiers\/#11-taille-de-restructuration>Taille de restructuration<\/a><\/li><\/ul><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/tailler-les-arbres-fruitiers\/#12-avec-quoi-taille-t-on-les-arbres-fruitiers->Avec quoi taille-t-on les arbres fruitiers&nbsp;?<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/tailler-les-arbres-fruitiers\/#13-taille-des-arbres-fruitiers-%E2%80%93-les-erreurs-%C3%A0-ne-pas-faire>Taille des arbres fruitiers \u2013 les erreurs \u00e0 ne pas faire<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/tailler-les-arbres-fruitiers\/#14-tailler-les-arbres-fruitiers-%E2%80%93-en-bref>Tailler les arbres fruitiers \u2013 En bref<\/a><\/li><\/ul><\/div><\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"0-pourquoi-tailler-les-arbres-fruitiers-\">Pourquoi tailler les arbres fruitiers&nbsp;?<\/h2>\n\n\n\n<p>La taille des arbres fruitiers contribue largement \u00e0 les maintenir en bonne sant\u00e9. En compl\u00e9ment, vous pouvez traiter les arbres afin de les <strong>prot\u00e9ger contre les maladies et les ravageurs<\/strong>.<\/p>\n\n\n\n<p>La taille des branches pr\u00e9sente de nombreux avantages. Elle \u00e9limine les pousses faibles, mortes ou malades. En outre, elle permet d&#8217;\u00e9claircir la canop\u00e9e et d&#8217;am\u00e9liorer l&#8217;<strong>apport d&#8217;air aux branches<\/strong> dans la couronne de l&#8217;arbre. Vous r\u00e9duisez ainsi le risque que des maladies se d\u00e9veloppent et se propagent dans le fouillis de feuilles et de pousses. Avant tout traitement, il est \u00e9galement important que la couronne soit clairsem\u00e9e afin que les produits atteignent chaque branche de l&#8217;arbre.<\/p>\n\n\n\n<p>La taille des arbres fruitiers <strong>vous permet de contr\u00f4ler leur croissance<\/strong>. Vous limitez ainsi la hauteur et l&#8217;\u00e9tendue de la couronne et rendez la r\u00e9colte suivante plus confortable. La taille stimule les arbres fruitiers \u00e0 former de nouvelles pousses. De m\u00eame, les fruits m\u00fbrissent beaucoup plus gros, plus color\u00e9s et plus sucr\u00e9s.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1-quand-tailler-les-arbres-fruitiers-\">Quand tailler les arbres fruitiers&nbsp;?<\/h2>\n\n\n\n<p>Il n&#8217;est pas si facile de d\u00e9terminer un moment unique pour tailler les arbres fruitiers, car cela d\u00e9pend de l&#8217;esp\u00e8ce d&#8217;arbre et parfois m\u00eame de la vari\u00e9t\u00e9. C&#8217;est pourquoi vous entretenez diff\u00e9rents arbres fruitiers \u00e0 diff\u00e9rents moments de l&#8217;ann\u00e9e.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"2-quel-est-le-meilleur-moment-pour-tailler-les-pommiers-\">Quel est le meilleur moment pour tailler les pommiers&nbsp;?<\/h3>\n\n\n\n<p>Les pommiers doivent \u00eatre taill\u00e9s <strong>deux fois par an<\/strong>. La premi\u00e8re taille se fait en hiver, de pr\u00e9f\u00e9rence fin f\u00e9vrier. L&#8217;arbre est alors encore au repos, de sorte qu&#8217;une taille intensive des branches ne le d\u00e9range pas. Au printemps suivant, le pommier commence \u00e0 pousser abondamment et se r\u00e9g\u00e9n\u00e8re compl\u00e8tement apr\u00e8s la taille.<\/p>\n\n\n\n<p>Vous effectuez la deuxi\u00e8me taille du pommier en \u00e9t\u00e9. Apr\u00e8s la taille hivernale, un grand nombre de pousses poussent sur l&#8217;arbre, dont vous enlevez la plupart pour <strong>d\u00e9gager la couronne<\/strong> et permettre \u00e0 la lumi\u00e8re d&#8217;atteindre les fruits. Ce traitement est sans danger pour l&#8217;arbre&nbsp;: l&#8217;air est assez sec en \u00e9t\u00e9, vous n&#8217;avez donc pas \u00e0 vous soucier d&#8217;une infection par des maladies fongiques.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"3-taillez-les-poiriers-comme-les-pommiers\">Taillez les poiriers comme les pommiers<\/h3>\n\n\n\n<p>Vous traitez les poiriers <strong>\u00e0 la m\u00eame p\u00e9riode que les pommiers<\/strong>. C&#8217;est pourquoi vous effectuez la premi\u00e8re taille de la couronne, plus vigoureuse, au changement de saison en f\u00e9vrier\/mars et la deuxi\u00e8me, plus l\u00e9g\u00e8re, entre juillet et ao\u00fbt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"4-le-bon-moment-pour-tailler-les-p%C3%AAchers-et-les-abricotiers\">Le bon moment pour tailler les p\u00eachers et les abricotiers<\/h3>\n\n\n\n<p>Pour tailler les arbres fruitiers sensibles au gel, il faut attendre un peu plus tard que la taille des poiriers et des pommiers. Comme les p\u00eachers, les abricotiers et les nectariniers sont originaires de r\u00e9gions plus chaudes d&#8217;Europe, <strong>ils ne doivent pas \u00eatre expos\u00e9s \u00e0 des temp\u00e9ratures basses apr\u00e8s la taille<\/strong>. C&#8217;est pourquoi il est pr\u00e9f\u00e9rable de les couper un peu plus tard, en avril.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"5-taille-dentretien-des-cerisiers-en-%C3%A9t%C3%A9\">Taille d&#8217;entretien des cerisiers en \u00e9t\u00e9<\/h3>\n\n\n\n<p>Les cerisiers sont tr\u00e8s sensibles aux maladies et les attaques bact\u00e9riennes sont particuli\u00e8rement dangereuses pour eux. C&#8217;est pourquoi il est recommand\u00e9 de les tailler en \u00e9t\u00e9, <strong>apr\u00e8s avoir r\u00e9colt\u00e9 les fruits<\/strong>. Il est pr\u00e9f\u00e9rable de choisir un jour sec et chaud, fin juillet ou d\u00e9but ao\u00fbt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"6-quand-tailler-un-prunier-\">Quand tailler un prunier&nbsp;?<\/h3>\n\n\n\n<p>La r\u00e9ponse est moins tranch\u00e9e, le moment de la taille <strong>d\u00e9pend de la<\/strong> <strong>vari\u00e9t\u00e9<\/strong>&nbsp;:<strong> \u00e0 maturit\u00e9 pr\u00e9coce ou tardive<\/strong>. Pour le premier type de pruniers, taillez directement apr\u00e8s la r\u00e9colte des fruits, fin ao\u00fbt ou d\u00e9but septembre. Pour les pruniers \u00e0 maturit\u00e9 tardive, il est recommand\u00e9 de proc\u00e9der \u00e0 une taille d&#8217;entretien fin mars ou d\u00e9but avril.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n        <div id=\"block_b6f369ce2cf992f0c8d4b6904c8384d1\" class=\"wpmagus-block expondo-block expondo-block-photo-with-hotspots\">\n          <div\n            class=\"wpmagus-block__inner-container expondo-block__inner-container photo-with-hotspots-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.expondo.fr\/inspirations\/wp-content\/uploads\/2022\/03\/10090081-7-1088x725.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.expondo.fr\/inspirations\/wp-content\/uploads\/2022\/03\/10090081-7-1088x725.jpg 1088w, https:\/\/www.expondo.fr\/inspirations\/wp-content\/uploads\/2022\/03\/10090081-7-300x200.jpg 300w, https:\/\/www.expondo.fr\/inspirations\/wp-content\/uploads\/2022\/03\/10090081-7-768x512.jpg 768w, https:\/\/www.expondo.fr\/inspirations\/wp-content\/uploads\/2022\/03\/10090081-7-1536x1024.jpg 1536w, https:\/\/www.expondo.fr\/inspirations\/wp-content\/uploads\/2022\/03\/10090081-7.jpg 1548w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>            <ul class=\"list list--hotspots\">\n                              <li class=\"item\" style=\"left: 40.00%; top: 32.00%;\">\n                  <button class=\"hotspot\"\n                    style=\"background-color: #dd9933\"\n                    >+<\/button>\n                  <div class=\"description\" style=\"position:relative;z-index:10;padding:24px;\">\n                                                                              <\/div>\n                <\/li>\n                          <\/ul>\n                          <div class=\"description description--mob\"\n                style=\"display: none!important;position: relative; z-index: 10;transform: translateY(-50%);margin: 0 10%;padding: 2rem;border-radius: 8px;\">\n                                                              <\/div>\n                      <\/div>\n        <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n        <div id=\"block_ddb8a14c63c54946aa1d7cdb9b05ad2b\" class=\"wpmagus-block expondo-block expondo-block-photo-with-hotspots\">\n          <div\n            class=\"wpmagus-block__inner-container expondo-block__inner-container photo-with-hotspots-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.expondo.fr\/inspirations\/wp-content\/uploads\/2022\/03\/10090082-8-1088x726.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.expondo.fr\/inspirations\/wp-content\/uploads\/2022\/03\/10090082-8-1088x726.jpg 1088w, https:\/\/www.expondo.fr\/inspirations\/wp-content\/uploads\/2022\/03\/10090082-8-300x200.jpg 300w, https:\/\/www.expondo.fr\/inspirations\/wp-content\/uploads\/2022\/03\/10090082-8-768x512.jpg 768w, https:\/\/www.expondo.fr\/inspirations\/wp-content\/uploads\/2022\/03\/10090082-8.jpg 1103w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>            <ul class=\"list list--hotspots\">\n                              <li class=\"item\" style=\"left: 48.00%; top: 34.00%;\">\n                  <button class=\"hotspot\"\n                    style=\"background-color: #dd9933\"\n                    >+<\/button>\n                  <div class=\"description\" style=\"position:relative;z-index:10;padding:24px;\">\n                                                                              <\/div>\n                <\/li>\n                          <\/ul>\n                          <div class=\"description description--mob\"\n                style=\"display: none!important;position: relative; z-index: 10;transform: translateY(-50%);margin: 0 10%;padding: 2rem;border-radius: 8px;\">\n                                                              <\/div>\n                      <\/div>\n        <\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"7-comment-tailler-les-arbres-fruitiers-\">Comment tailler les arbres fruitiers&nbsp;?<\/h2>\n\n\n\n<p>Il est important de tailler les arbres fruitiers r\u00e9guli\u00e8rement. De temps en temps, les plantes ont besoin d&#8217;une <strong>taille de rajeunissement<\/strong> approfondie. Mais il arrive aussi qu&#8217;une taille impr\u00e9vue soit n\u00e9cessaire. D\u00e9couvrez quels types de taille des arbres fruitiers sont possibles tout au long de l&#8217;ann\u00e9e.<\/p>\n\n\n              <div id=\"expondo-products-block_d986199dcfdacae846fc10ff5d312bd1\" class=\"expondo-block expondo-block--products\">\n          <div class=\"expondo-block__inner-container\">\n            <ul class=\"list list--products\">\n                              <li class=\"item\">\n                  <a href=\"\/hillvert-epandeur-engrais-14-l-largeur-d-epandage-de-1-a-3-m-10090135\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10090135_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/hillvert-epandeur-engrais-14-l-largeur-d-epandage-de-1-a-3-m-10090135\">\n                        \u00c9pandeur engrais &#8211; 15 l &#8211; Largeur d\u2019\u00e9pandage de 1 \u00e0 3 m                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                              <ins>77.00&nbsp;\u20ac<\/ins>\n                    <\/span>\n                                  <\/li>\n                          <\/ul>\n          <\/div>\n        <\/div>\n        \n\n\n<h3 class=\"wp-block-heading\" id=\"8-taille-de-rajeunissement\">Taille de rajeunissement<\/h3>\n\n\n\n<p>Une taille radicale des vieux arbres fruitiers doit \u00eatre effectu\u00e9e de temps en temps. Le sentimentalisme n&#8217;a pas sa place ici&nbsp;: <strong>supprimez les branches et les rameaux les plus anciens<\/strong> et raccourcissez nettement les autres. Heureusement, il n&#8217;est pas n\u00e9cessaire de rajeunir les arbres fruitiers en une seule taille. Vous pouvez sans probl\u00e8me r\u00e9partir l&#8217;ensemble du processus sur deux ou m\u00eame trois saisons.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"9-taille-de-formation\">Taille de formation<\/h3>\n\n\n\n<p>Tailler les arbres fruitiers de mani\u00e8re que leur couronne soit uniform\u00e9ment r\u00e9partie et que leur tronc soit clairement d\u00e9limit\u00e9 pr\u00e9sente de nombreux avantages. La taille de formation assure une croissance correcte de l&#8217;arbre, elle fournit aux pousses la bonne quantit\u00e9 de lumi\u00e8re et influence ainsi positivement la formation des fruits. Par ailleurs, la taille de formation am\u00e9liore <strong>l&#8217;apparence des arbres fruitiers<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"10-taille-sanitaire-et-taille-dentretien\">Taille sanitaire et taille d&#8217;entretien<\/h3>\n\n\n\n<p>Vous effectuez r\u00e9guli\u00e8rement la taille d&#8217;entretien des arbres fruitiers afin d&#8217;\u00e9liminer les pousses cass\u00e9es, faibles, fan\u00e9es ou attaqu\u00e9es par des parasites. La <strong>taille sanitaire<\/strong> a lieu en r\u00e9ponse \u00e0 une maladie de l&#8217;arbre. Elle doit \u00eatre effectu\u00e9e lorsque vous constatez que des pousses risquent de devenir un foyer d&#8217;infection qui affectera l&#8217;ensemble de l&#8217;arbre.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"11-taille-de-restructuration\">Taille de restructuration<\/h3>\n\n\n\n<p>Les vieux arbres fruitiers auxquels on ne pr\u00eate gu\u00e8re attention et les arbres ayant souffert lors de temp\u00eates ont souvent besoin d&#8217;une taille de restructuration pour leur redonner une forme attrayante et une pleine sant\u00e9. <strong>Supprimez les pousses exub\u00e9rantes<\/strong> qui d\u00e9passent la forme de la couronne et les branches qui poussent \u00e0 l&#8217;int\u00e9rieur de l&#8217;arbre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"12-avec-quoi-taille-t-on-les-arbres-fruitiers-\">Avec quoi taille-t-on les arbres fruitiers&nbsp;?<\/h2>\n\n\n\n<p>Quels <mdspan datatext=\"el1730187718405\" class=\"mdspan-comment\"><a href=\"https:\/\/www.expondo.fr\/outil-de-jardinage\/\" target=\"_blank\" rel=\"noreferrer noopener\">outils de jardinage<\/a><\/mdspan> choisir pour \u00e9laguer les arbres fruitiers\u00a0? <strong>Diff\u00e9rents types de s\u00e9cateurs<\/strong> sont n\u00e9cessaires, que vous pourrez \u00e9galement utiliser pour d&#8217;autres t\u00e2ches.<\/p>\n\n\n\n<p>Les petits s\u00e9cateurs, plus maniables, permettent de couper les pousses indisciplin\u00e9es qui ne fleurissent pas ou ne portent pas de fruits. Ils conviennent aussi pour des coupes pr\u00e9cises, par exemple pour la taille de <mdspan datatext=\"el1730188030242\" class=\"mdspan-comment\"><a href=\"https:\/\/www.expondo.fr\/inspirations\/tailler-les-coniferes-quand-et-comment-le-faire\/\" target=\"_blank\" rel=\"noreferrer noopener\">conif\u00e8res<\/a><\/mdspan>. Pour \u00e9liminer les branches l\u00e9g\u00e8rement lignifi\u00e9es, optez pour des ciseaux plus grands et plus robustes. <strong>Les s\u00e9cateurs \u00e0 deux mains restent irrempla\u00e7ables pour couper les vieilles branches<\/strong>. Pour les bois tr\u00e8s \u00e9pais, la force manuelle ne suffit souvent pas. Tout comme le taille-haie pour l&#8217;<mdspan datatext=\"el1730188068295\" class=\"mdspan-comment\"><a href=\"https:\/\/www.expondo.fr\/inspirations\/comment-tailler-une-haie-guide-de-conseils-et-doutils\/\" target=\"_blank\" rel=\"noreferrer noopener\">entretien des haies<\/a><\/mdspan>, la tron\u00e7onneuse est une aide irrempla\u00e7able pour les arbres.<\/p>\n\n\n\n<p>Ces outils de base sont suffisants pour effectuer tous les travaux li\u00e9s \u00e0 la taille des arbres fruitiers. Pensez \u00e0 <strong>d\u00e9sinfecter<\/strong> les <strong>lames du s\u00e9cateur apr\u00e8s chaque utilisation<\/strong>, vous \u00e9viterez ainsi que des maladies ne se propagent entre les plantes dans le jardin.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"13-taille-des-arbres-fruitiers-%E2%80%93-les-erreurs-%C3%A0-ne-pas-faire\">Taille des arbres fruitiers \u2013 les erreurs \u00e0 ne pas faire<\/h2>\n\n\n\n<p>La plus grande erreur que peuvent commettre les personnes inexp\u00e9riment\u00e9es est de tailler les arbres fruitiers en automne. Cette p\u00e9riode de l&#8217;ann\u00e9e n&#8217;est pas propice \u00e0 ce type de travaux, car l&#8217;air humide favorise la <strong>propagation de diverses maladies fongiques<\/strong>, notamment sur les arbres taill\u00e9s.<\/p>\n\n\n\n<p>En outre, les premi\u00e8res gel\u00e9es affaiblissent les arbres fruitiers au niveau des coupes avant qu&#8217;ils ne gu\u00e9rissent et ne se r\u00e9g\u00e9n\u00e8rent. <strong>En hiver, le gel n&#8217;est pas aussi dangereux<\/strong>, les arbres \u00e9tant alors au repos. En automne, en revanche, vous avez affaire \u00e0 des arbres encore pleins de vitalit\u00e9.<\/p>\n\n\n\n<p>La deuxi\u00e8me erreur consiste \u00e0 ne pas tenir compte des conditions m\u00e9t\u00e9orologiques lors de la taille estivale. Cela ne vaut pas seulement pour la taille des arbres fruitiers, mais aussi pour toutes les autres plantes du jardin.<\/p>\n\n\n\n<p>Taillez toujours les arbres fruitiers avec des outils tranchants, les lames \u00e9mouss\u00e9es emp\u00eachent les coupes nettes, \u00e9crasent les pousses et les endommagent durablement.<\/p>\n\n\n              <div id=\"expondo-products-block_d73eba534c842f6b3b999624a842b749\" class=\"expondo-block expondo-block--products\">\n          <div class=\"expondo-block__inner-container\">\n            <ul class=\"list list--products\">\n                              <li class=\"item\">\n                  <a href=\"\/msw-enrouleur-de-cable-automatique-20-m-1-5-m-10060680\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10060680_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/msw-enrouleur-de-cable-automatique-20-m-1-5-m-10060680\">\n                        Enrouleur de c\u00e2ble &#8211; automatique &#8211; 20 m + 1,5 m                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                              <ins>77.00&nbsp;\u20ac<\/ins>\n                    <\/span>\n                                  <\/li>\n                          <\/ul>\n          <\/div>\n        <\/div>\n        \n\n\n<h2 class=\"wp-block-heading\" id=\"14-tailler-les-arbres-fruitiers-%E2%80%93-en-bref\">Tailler les arbres fruitiers \u2013 En bref<\/h2>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Petrol Wood Chipper hillvert HT-HECTOR 212 | Product presentation\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/BYKWi2ceMPo?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/www.expondo.co.uk\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p>Si vous voulez que votre verger soit couvert de fleurs au printemps et vous offre une r\u00e9colte abondante en automne, vous devez <strong>tailler r\u00e9guli\u00e8rement<\/strong> <strong>vos arbres fruitiers<\/strong>. En \u00e9t\u00e9, le jardin fleurit alors dans toute sa splendeur. La taille permet de maintenir les plantes en bonne sant\u00e9. Elle stimule la croissance et prot\u00e8ge les arbres des maladies fongiques.<\/p>\n\n\n\n<p>Gr\u00e2ce aux conseils ci-dessus, vous saurez quand tailler les arbres fruitiers de diff\u00e9rentes esp\u00e8ces et quels types de taille utiliser au mieux. Mettez-les en pratique et <strong>profitez d&#8217;arbres beaux et riches en fruits<\/strong>.<\/p>\n\n\n\n<p>N&#8217;oubliez pas que le ramassage des pousses et des branches coup\u00e9es est aussi important pour votre jardin que le <mdspan datatext=\"el1730189960743\" class=\"mdspan-comment\"><a href=\"https:\/\/www.expondo.fr\/inspirations\/rammaser-les-feuilles-mortes\/\" target=\"_blank\" rel=\"noreferrer noopener\">ramassage des feuilles mortes<\/a><\/mdspan>\u00a0!<\/p>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous voulez planter des arbres fruitiers sur votre terrain&nbsp;? Dans ce cas, pr\u00e9parez-vous \u00e0 beaucoup de&hellip;<\/p>\n","protected":false},"author":21,"featured_media":25537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_sb_is_suggestion_mode":false,"_sb_show_suggestion_boards":false,"_sb_show_comment_boards":false,"_sb_suggestion_history":"","_sb_update_block_changes":"","ub_ctt_via":"","rank_math_lock_modified_date":false,"_strive_post_notes":"580\r\nLinks\r\n1. \r\nhttps:\/\/www.expondo.de\/gartengeraete\/\r\nhttps:\/\/www.expondo.co.uk\/garden-tools\/\r\nhttps:\/\/www.expondo.fr\/outil-de-jardinage\/\r\nhttps:\/\/www.expondo.it\/attrezzi-da-giardino\/\r\nhttps:\/\/www.expondo.se\/traedgaardsredskap\/\r\nhttps:\/\/www.expondo.hu\/kerti-eszkoezoek-1d5f0408\/\r\n\r\n\r\n2. 366 - \r\n\r\nSE and IT not ordered yet - leave a comment ID 366\r\n\r\nhttps:\/\/www.expondo.co.uk\/inspirations\/when-and-how-to-prune-conifers\/\r\n\r\nhttps:\/\/www.expondo.de\/inspirationen\/nadelbaume-richtig-beschneiden\/\r\n\r\nhttps:\/\/www.expondo.fr\/inspirations\/tailler-les-coniferes-quand-et-comment-le-faire\/\r\n\r\nhttps:\/\/www.expondo.ie\/inspirations\/when-and-how-to-prune-conifers\/\r\n\r\nhttps:\/\/www.expondo.at\/inspirationen\/nadelbaume-richtig-beschneiden\/\r\n\r\nhttps:\/\/www.expondo.be\/inspirations\/tailler-les-coniferes-quand-et-comment-le-faire\/\r\n\r\nhttps:\/\/www.expondo.hu\/inspiraciok\/mikor-es-hogyan-metszuk-a-diszcserjeket\/\r\n\r\n3. 279 - \r\nSE and IT not ordered yet - leave a comment ID 279\r\n\r\nhttps:\/\/www.expondo.co.uk\/inspirations\/how-to-trim-a-hedge-guide-to-the-best-tools-and-techniques\/\r\n\r\nhttps:\/\/www.expondo.de\/inspirationen\/hecke-richtig-schneiden\/\r\n\r\nhttps:\/\/www.expondo.fr\/inspirations\/comment-tailler-une-haie-guide-de-conseils-et-doutils\/\r\n\r\nhttps:\/\/www.expondo.ie\/inspirations\/how-to-trim-a-hedge-guide-to-the-best-tools-and-techniques\/\r\n\r\nhttps:\/\/www.expondo.at\/inspirationen\/hecke-richtig-schneiden\/\r\n\r\nhttps:\/\/www.expondo.be\/inspirations\/comment-tailler-une-haie-guide-de-conseils-et-doutils\/\r\n\r\nhttps:\/\/www.expondo.hu\/inspiraciok\/soveny-nyiras-helyesen\/\r\n\r\n4. 364 \r\n\r\nSE and IT not ordered yet - leave a comment ID 364\r\n\r\nhttps:\/\/www.expondo.co.uk\/inspirations\/raking-leaves\/\r\n\r\nhttps:\/\/www.expondo.de\/inspirationen\/laub-harken-pro-und-kontra\/\r\n\r\nhttps:\/\/www.expondo.fr\/inspirations\/rammaser-les-feuilles-mortes\/\r\n\r\nhttps:\/\/www.expondo.ie\/inspirations\/raking-leaves\/\r\n\r\nhttps:\/\/www.expondo.at\/inspirationen\/laub-harken-pro-und-kontra\/\r\n\r\nhttps:\/\/www.expondo.be\/inspirations\/rammaser-les-feuilles-mortes\/\r\n\r\nhttps:\/\/www.expondo.hu\/inspiraciok\/levelek-gereblyezese-hogyan-es-mikor\/","footnotes":""},"categories":[2846],"tags":[],"promotion":[],"class_list":["post-87588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-maison-et-jardin"],"acf":[],"featured_image_src":"https:\/\/www.expondo.fr\/inspirations\/wp-content\/uploads\/2022\/03\/how-and-when-to-prune-fruit-trees.jpg","author_info":{"display_name":"Aleksandra Mojka","author_link":"https:\/\/www.expondo.fr\/inspirations\/author\/aleksandra-mojka\/"},"reading_time":"8","author_thumbnail":"https:\/\/secure.gravatar.com\/avatar\/c6bea5b84cf5de4bc1f64d8190012798?s=96&d=mm&r=g","excerpt_full":"\n<p><strong>Vous voulez planter des arbres fruitiers sur votre terrain<\/strong>&nbsp;<strong>? Dans ce cas, pr\u00e9parez-vous \u00e0 beaucoup de travail chaque ann\u00e9e. Au printemps, vos arbres seront couverts de fleurs qui donneront de d\u00e9licieux fruits en automne. L'une des t\u00e2ches consiste \u00e0 tailler les arbres. Mais quel est le bon moment pour le faire et comment s'y prendre ?<\/strong><\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"0-pourquoi-tailler-les-arbres-fruitiers-\">Pourquoi tailler les arbres fruitiers&nbsp;?<\/h2>\n\n\n\n<p>La taille des arbres fruitiers contribue largement \u00e0 les maintenir en bonne sant\u00e9. En compl\u00e9ment, vous pouvez traiter les arbres afin de les <strong>prot\u00e9ger contre les maladies et les ravageurs<\/strong>.<\/p>\n\n\n\n<p>La taille des branches pr\u00e9sente de nombreux avantages. Elle \u00e9limine les pousses faibles, mortes ou malades. En outre, elle permet d'\u00e9claircir la canop\u00e9e et d'am\u00e9liorer l'<strong>apport d'air aux branches<\/strong> dans la couronne de l'arbre. Vous r\u00e9duisez ainsi le risque que des maladies se d\u00e9veloppent et se propagent dans le fouillis de feuilles et de pousses. Avant tout traitement, il est \u00e9galement important que la couronne soit clairsem\u00e9e afin que les produits atteignent chaque branche de l'arbre.<\/p>\n\n\n\n<p>La taille des arbres fruitiers <strong>vous permet de contr\u00f4ler leur croissance<\/strong>. Vous limitez ainsi la hauteur et l'\u00e9tendue de la couronne et rendez la r\u00e9colte suivante plus confortable. La taille stimule les arbres fruitiers \u00e0 former de nouvelles pousses. De m\u00eame, les fruits m\u00fbrissent beaucoup plus gros, plus color\u00e9s et plus sucr\u00e9s.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1-quand-tailler-les-arbres-fruitiers-\">Quand tailler les arbres fruitiers&nbsp;?<\/h2>\n\n\n\n<p>Il n'est pas si facile de d\u00e9terminer un moment unique pour tailler les arbres fruitiers, car cela d\u00e9pend de l'esp\u00e8ce d'arbre et parfois m\u00eame de la vari\u00e9t\u00e9. C'est pourquoi vous entretenez diff\u00e9rents arbres fruitiers \u00e0 diff\u00e9rents moments de l'ann\u00e9e.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"2-quel-est-le-meilleur-moment-pour-tailler-les-pommiers-\">Quel est le meilleur moment pour tailler les pommiers&nbsp;?<\/h3>\n\n\n\n<p>Les pommiers doivent \u00eatre taill\u00e9s <strong>deux fois par an<\/strong>. La premi\u00e8re taille se fait en hiver, de pr\u00e9f\u00e9rence fin f\u00e9vrier. L'arbre est alors encore au repos, de sorte qu'une taille intensive des branches ne le d\u00e9range pas. Au printemps suivant, le pommier commence \u00e0 pousser abondamment et se r\u00e9g\u00e9n\u00e8re compl\u00e8tement apr\u00e8s la taille.<\/p>\n\n\n\n<p>Vous effectuez la deuxi\u00e8me taille du pommier en \u00e9t\u00e9. Apr\u00e8s la taille hivernale, un grand nombre de pousses poussent sur l'arbre, dont vous enlevez la plupart pour <strong>d\u00e9gager la couronne<\/strong> et permettre \u00e0 la lumi\u00e8re d'atteindre les fruits. Ce traitement est sans danger pour l'arbre&nbsp;: l'air est assez sec en \u00e9t\u00e9, vous n'avez donc pas \u00e0 vous soucier d'une infection par des maladies fongiques.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"3-taillez-les-poiriers-comme-les-pommiers\">Taillez les poiriers comme les pommiers<\/h3>\n\n\n\n<p>Vous traitez les poiriers <strong>\u00e0 la m\u00eame p\u00e9riode que les pommiers<\/strong>. C'est pourquoi vous effectuez la premi\u00e8re taille de la couronne, plus vigoureuse, au changement de saison en f\u00e9vrier\/mars et la deuxi\u00e8me, plus l\u00e9g\u00e8re, entre juillet et ao\u00fbt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"4-le-bon-moment-pour-tailler-les-p%C3%AAchers-et-les-abricotiers\">Le bon moment pour tailler les p\u00eachers et les abricotiers<\/h3>\n\n\n\n<p>Pour tailler les arbres fruitiers sensibles au gel, il faut attendre un peu plus tard que la taille des poiriers et des pommiers. Comme les p\u00eachers, les abricotiers et les nectariniers sont originaires de r\u00e9gions plus chaudes d'Europe, <strong>ils ne doivent pas \u00eatre expos\u00e9s \u00e0 des temp\u00e9ratures basses apr\u00e8s la taille<\/strong>. C'est pourquoi il est pr\u00e9f\u00e9rable de les couper un peu plus tard, en avril.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"5-taille-dentretien-des-cerisiers-en-%C3%A9t%C3%A9\">Taille d'entretien des cerisiers en \u00e9t\u00e9<\/h3>\n\n\n\n<p>Les cerisiers sont tr\u00e8s sensibles aux maladies et les attaques bact\u00e9riennes sont particuli\u00e8rement dangereuses pour eux. C'est pourquoi il est recommand\u00e9 de les tailler en \u00e9t\u00e9, <strong>apr\u00e8s avoir r\u00e9colt\u00e9 les fruits<\/strong>. Il est pr\u00e9f\u00e9rable de choisir un jour sec et chaud, fin juillet ou d\u00e9but ao\u00fbt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"6-quand-tailler-un-prunier-\">Quand tailler un prunier&nbsp;?<\/h3>\n\n\n\n<p>La r\u00e9ponse est moins tranch\u00e9e, le moment de la taille <strong>d\u00e9pend de la<\/strong> <strong>vari\u00e9t\u00e9<\/strong>&nbsp;:<strong> \u00e0 maturit\u00e9 pr\u00e9coce ou tardive<\/strong>. Pour le premier type de pruniers, taillez directement apr\u00e8s la r\u00e9colte des fruits, fin ao\u00fbt ou d\u00e9but septembre. Pour les pruniers \u00e0 maturit\u00e9 tardive, il est recommand\u00e9 de proc\u00e9der \u00e0 une taille d'entretien fin mars ou d\u00e9but avril.<\/p>\n\n\n\n<div class=\"wp-block-columns\">\n\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"7-comment-tailler-les-arbres-fruitiers-\">Comment tailler les arbres fruitiers&nbsp;?<\/h2>\n\n\n\n<p>Il est important de tailler les arbres fruitiers r\u00e9guli\u00e8rement. De temps en temps, les plantes ont besoin d'une <strong>taille de rajeunissement<\/strong> approfondie. Mais il arrive aussi qu'une taille impr\u00e9vue soit n\u00e9cessaire. D\u00e9couvrez quels types de taille des arbres fruitiers sont possibles tout au long de l'ann\u00e9e.<\/p>\n\n\n\n\n\n<h3 class=\"wp-block-heading\" id=\"8-taille-de-rajeunissement\">Taille de rajeunissement<\/h3>\n\n\n\n<p>Une taille radicale des vieux arbres fruitiers doit \u00eatre effectu\u00e9e de temps en temps. Le sentimentalisme n'a pas sa place ici&nbsp;: <strong>supprimez les branches et les rameaux les plus anciens<\/strong> et raccourcissez nettement les autres. Heureusement, il n'est pas n\u00e9cessaire de rajeunir les arbres fruitiers en une seule taille. Vous pouvez sans probl\u00e8me r\u00e9partir l'ensemble du processus sur deux ou m\u00eame trois saisons.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"9-taille-de-formation\">Taille de formation<\/h3>\n\n\n\n<p>Tailler les arbres fruitiers de mani\u00e8re que leur couronne soit uniform\u00e9ment r\u00e9partie et que leur tronc soit clairement d\u00e9limit\u00e9 pr\u00e9sente de nombreux avantages. La taille de formation assure une croissance correcte de l'arbre, elle fournit aux pousses la bonne quantit\u00e9 de lumi\u00e8re et influence ainsi positivement la formation des fruits. Par ailleurs, la taille de formation am\u00e9liore <strong>l'apparence des arbres fruitiers<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"10-taille-sanitaire-et-taille-dentretien\">Taille sanitaire et taille d'entretien<\/h3>\n\n\n\n<p>Vous effectuez r\u00e9guli\u00e8rement la taille d'entretien des arbres fruitiers afin d'\u00e9liminer les pousses cass\u00e9es, faibles, fan\u00e9es ou attaqu\u00e9es par des parasites. La <strong>taille sanitaire<\/strong> a lieu en r\u00e9ponse \u00e0 une maladie de l'arbre. Elle doit \u00eatre effectu\u00e9e lorsque vous constatez que des pousses risquent de devenir un foyer d'infection qui affectera l'ensemble de l'arbre.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"11-taille-de-restructuration\">Taille de restructuration<\/h3>\n\n\n\n<p>Les vieux arbres fruitiers auxquels on ne pr\u00eate gu\u00e8re attention et les arbres ayant souffert lors de temp\u00eates ont souvent besoin d'une taille de restructuration pour leur redonner une forme attrayante et une pleine sant\u00e9. <strong>Supprimez les pousses exub\u00e9rantes<\/strong> qui d\u00e9passent la forme de la couronne et les branches qui poussent \u00e0 l'int\u00e9rieur de l'arbre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"12-avec-quoi-taille-t-on-les-arbres-fruitiers-\">Avec quoi taille-t-on les arbres fruitiers&nbsp;?<\/h2>\n\n\n\n<p>Quels <mdspan datatext=\"el1730187718405\" class=\"mdspan-comment\"><a href=\"https:\/\/www.expondo.fr\/outil-de-jardinage\/\" target=\"_blank\" rel=\"noreferrer noopener\">outils de jardinage<\/a><\/mdspan> choisir pour \u00e9laguer les arbres fruitiers\u00a0? <strong>Diff\u00e9rents types de s\u00e9cateurs<\/strong> sont n\u00e9cessaires, que vous pourrez \u00e9galement utiliser pour d'autres t\u00e2ches.<\/p>\n\n\n\n<p>Les petits s\u00e9cateurs, plus maniables, permettent de couper les pousses indisciplin\u00e9es qui ne fleurissent pas ou ne portent pas de fruits. Ils conviennent aussi pour des coupes pr\u00e9cises, par exemple pour la taille de <mdspan datatext=\"el1730188030242\" class=\"mdspan-comment\"><a href=\"https:\/\/www.expondo.fr\/inspirations\/tailler-les-coniferes-quand-et-comment-le-faire\/\" target=\"_blank\" rel=\"noreferrer noopener\">conif\u00e8res<\/a><\/mdspan>. Pour \u00e9liminer les branches l\u00e9g\u00e8rement lignifi\u00e9es, optez pour des ciseaux plus grands et plus robustes. <strong>Les s\u00e9cateurs \u00e0 deux mains restent irrempla\u00e7ables pour couper les vieilles branches<\/strong>. Pour les bois tr\u00e8s \u00e9pais, la force manuelle ne suffit souvent pas. Tout comme le taille-haie pour l'<mdspan datatext=\"el1730188068295\" class=\"mdspan-comment\"><a href=\"https:\/\/www.expondo.fr\/inspirations\/comment-tailler-une-haie-guide-de-conseils-et-doutils\/\" target=\"_blank\" rel=\"noreferrer noopener\">entretien des haies<\/a><\/mdspan>, la tron\u00e7onneuse est une aide irrempla\u00e7able pour les arbres.<\/p>\n\n\n\n<p>Ces outils de base sont suffisants pour effectuer tous les travaux li\u00e9s \u00e0 la taille des arbres fruitiers. Pensez \u00e0 <strong>d\u00e9sinfecter<\/strong> les <strong>lames du s\u00e9cateur apr\u00e8s chaque utilisation<\/strong>, vous \u00e9viterez ainsi que des maladies ne se propagent entre les plantes dans le jardin.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"13-taille-des-arbres-fruitiers-%E2%80%93-les-erreurs-%C3%A0-ne-pas-faire\">Taille des arbres fruitiers \u2013 les erreurs \u00e0 ne pas faire<\/h2>\n\n\n\n<p>La plus grande erreur que peuvent commettre les personnes inexp\u00e9riment\u00e9es est de tailler les arbres fruitiers en automne. Cette p\u00e9riode de l'ann\u00e9e n'est pas propice \u00e0 ce type de travaux, car l'air humide favorise la <strong>propagation de diverses maladies fongiques<\/strong>, notamment sur les arbres taill\u00e9s.<\/p>\n\n\n\n<p>En outre, les premi\u00e8res gel\u00e9es affaiblissent les arbres fruitiers au niveau des coupes avant qu'ils ne gu\u00e9rissent et ne se r\u00e9g\u00e9n\u00e8rent. <strong>En hiver, le gel n'est pas aussi dangereux<\/strong>, les arbres \u00e9tant alors au repos. En automne, en revanche, vous avez affaire \u00e0 des arbres encore pleins de vitalit\u00e9.<\/p>\n\n\n\n<p>La deuxi\u00e8me erreur consiste \u00e0 ne pas tenir compte des conditions m\u00e9t\u00e9orologiques lors de la taille estivale. Cela ne vaut pas seulement pour la taille des arbres fruitiers, mais aussi pour toutes les autres plantes du jardin.<\/p>\n\n\n\n<p>Taillez toujours les arbres fruitiers avec des outils tranchants, les lames \u00e9mouss\u00e9es emp\u00eachent les coupes nettes, \u00e9crasent les pousses et les endommagent durablement.<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"14-tailler-les-arbres-fruitiers-%E2%80%93-en-bref\">Tailler les arbres fruitiers \u2013 En bref<\/h2>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center\">\n\n<\/div>\n\n\n\n<p><\/p>\n","_links":{"self":[{"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/posts\/87588"}],"collection":[{"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/comments?post=87588"}],"version-history":[{"count":10,"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/posts\/87588\/revisions"}],"predecessor-version":[{"id":89600,"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/posts\/87588\/revisions\/89600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/media\/25537"}],"wp:attachment":[{"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/media?parent=87588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/categories?post=87588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/tags?post=87588"},{"taxonomy":"promotion","embeddable":true,"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/promotion?post=87588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}