{"id":11611,"date":"2021-09-02T06:11:00","date_gmt":"2021-09-02T06:11:00","guid":{"rendered":"https:\/\/www.expondo.co.uk\/inspirations\/jak-wybudowac-grill\/"},"modified":"2024-11-14T08:14:12","modified_gmt":"2024-11-14T08:14:12","slug":"comment-construire-son-barbecue","status":"publish","type":"post","link":"https:\/\/www.expondo.fr\/inspirations\/comment-construire-son-barbecue\/","title":{"rendered":"Comment faire un barbecue ?"},"content":{"rendered":"\n<p><strong>En \u00e9t\u00e9, les barbecues sont un \u00e9l\u00e9ment indissociable de chaque jardin. De nombreuses personnes utilisent encore des mod\u00e8les portables moins chers, mais les barbecues de jardin en briques fixes deviennent de plus en plus populaires. Ils permettent non seulement de pr\u00e9parer de d\u00e9licieux plats, mais ils constituent \u00e9galement une jolie d\u00e9coration de jardin. Dans cet article, vous apprendrez les conseils les plus importants qui vous seront utiles lors de la construction d&#8217;un barbecue.<\/strong><\/p>\n\n\n<div class=\"wp-block-ub-table-of-contents-block ub_table-of-contents\" data-showtext=\"show\" data-hidetext=\"hide\" data-scrolltype=\"auto\" id=\"ub_table-of-contents-68c52234-1ad8-49ea-9b25-e54e93443a47\" data-initiallyhideonmobile=\"false\"\n                    data-initiallyshow=\"true\"><div class=\"ub_table-of-contents-header-container\"><div class=\"ub_table-of-contents-header\">\n                    <div class=\"ub_table-of-contents-title\"><\/div><\/div><\/div><div class=\"ub_table-of-contents-extra-container\"><div class=\"ub_table-of-contents-container ub_table-of-contents-1-column \"><ul><li><a href=https:\/\/www.expondo.fr\/inspirations\/comment-construire-son-barbecue\/#0-construire-un-barbecue-types-de-barbecues-de-jardin>Construire un barbecue &#8211; types de barbecues de jardin<\/a><ul><li><a href=https:\/\/www.expondo.fr\/inspirations\/comment-construire-son-barbecue\/#1-comment-construire-un-barbecue-en-brique->Comment construire un barbecue en brique ?<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/comment-construire-son-barbecue\/#2-barbecue-en-clinker>Barbecue en clinker<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/comment-construire-son-barbecue\/#3-fabriquer-un-barbecue-en-pierre>Fabriquer un barbecue en pierre<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/comment-construire-son-barbecue\/#4-barbecue-avec-fumoir>Barbecue avec fumoir<\/a><\/li><\/ul><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/comment-construire-son-barbecue\/#5-fabriquer-son-barbecue-pas-%C3%A0-pas>Fabriquer son barbecue pas-\u00e0-pas<\/a><ul><li><a href=https:\/\/www.expondo.fr\/inspirations\/comment-construire-son-barbecue\/#6-%C3%A9quipement-indispensable-pour-faire-son-barbecue-de-jardin-soi-m%C3%AAme>\u00c9quipement indispensable pour faire son barbecue de jardin soi-m\u00eame<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/comment-construire-son-barbecue\/#7-outils-de-construction-de-barbecue-de-jardin>Outils de construction de barbecue de jardin<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/comment-construire-son-barbecue\/#8-comment-faire-un-barbecue-%C3%A9tape-1-%E2%80%93-projet>Comment faire un barbecue ? \u00c9tape 1 \u2013 projet<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/comment-construire-son-barbecue\/#9-comment-construire-un-barbecue-%C3%A9tape-2-%E2%80%93-fondations>Comment construire un barbecue ? \u00c9tape 2 \u2013 fondations<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/comment-construire-son-barbecue\/#10-comment-faire-son-barbecue-%C3%A9tape-3-%E2%80%93-ma%C3%A7onnerie>Comment faire son barbecue ? \u00c9tape 3 \u2013 ma\u00e7onnerie<\/a><\/li><\/ul><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/comment-construire-son-barbecue\/#11-de-quoi-dautre-il-vaut-penser-en-construisant-son-barbecue->De quoi d&#8217;autre il vaut penser en construisant son barbecue ?<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/comment-construire-son-barbecue\/#12-comment-construire-un-barbecue-avec-fumoir->Comment construire un barbecue avec fumoir ?<\/a><\/li><li><a href=https:\/\/www.expondo.fr\/inspirations\/comment-construire-son-barbecue\/#13-la-fabrication-d%E2%80%99un-barbecue-de-jardin-n%E2%80%99est-pas-difficile>La fabrication d\u2019un barbecue de jardin n\u2019est pas difficile<\/a><\/li><\/ul><\/div><\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"0-construire-un-barbecue-types-de-barbecues-de-jardin\">Construire un barbecue &#8211; types de barbecues de jardin<\/h2>\n\n\n\n<p>Lorsque vous d\u00e9cidez de fabriquer un <a href=\"https:\/\/www.expondo.fr\/barbecue-professionnel\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/www.expondo.fr\/barbecue-professionnel\/\" rel=\"noreferrer noopener\">barbecue <\/a>de jardin, il convient de conna\u00eetre ses diff\u00e9rents types.\u00a0 Ils diff\u00e8rent principalement par le mat\u00e9riau de fabrication et les \u00e9l\u00e9ments suppl\u00e9mentaires que vous pouvez inclure dans sa conception.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"1-comment-construire-un-barbecue-en-brique-\">Comment construire un barbecue en brique ?<\/h3>\n\n\n\n<p>L&#8217;un des mat\u00e9riaux les plus populaires utilis\u00e9s dans la construction d&#8217;un barbecue est la brique. Sa forme r\u00e9guli\u00e8re rend la ma\u00e7onnerie plus confortable et la structure relativement commode \u00e0 traiter facilite la d\u00e9coupe de pi\u00e8ces plus petites quand n\u00e9cessaire. Lorsque vous choisissez les bonnes briques, faites attention non seulement \u00e0 c\u00f4t\u00e9 esth\u00e9tique, mais \u00e9galement \u00e0 leur r\u00e9sistance aux temp\u00e9ratures \u00e9lev\u00e9es. Ceci est particuli\u00e8rement important \u00e0 proximit\u00e9 du foyer et de la grille. Les briques de chamotte seront parfaites.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"2-barbecue-en-clinker\">Barbecue en clinker<\/h3>\n\n\n\n<p>Les briques de clinker sont \u00e9galement un mat\u00e9riau de construction tr\u00e8s durable. Elles sont fabriqu\u00e9es \u00e0 tr\u00e8s haute temp\u00e9rature, ce qui conf\u00e8re au produit fini une r\u00e9sistance extraordinaire. En cons\u00e9quence, elle devient r\u00e9sistante non seulement \u00e0 la chaleur ou au froid, mais aussi \u00e0 l&#8217;eau. Cela signifie qu&#8217;un barbecue en clinker peut r\u00e9sister aux conditions m\u00e9t\u00e9orologiques les plus s\u00e9v\u00e8res en \u00e9t\u00e9 comme en hiver. Un autre avantage est leur apparence attrayante. Sur le march\u00e9, vous trouverez des briques de diff\u00e9rentes couleurs, gr\u00e2ce auxquelles vous construirez un barbecue original.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"3-fabriquer-un-barbecue-en-pierre\">Fabriquer un barbecue en pierre<\/h3>\n\n\n\n<p>La pierre naturelle est un choix tr\u00e8s courant lorsqu&#8217;il s&#8217;agit de mat\u00e9riau pour un barbecue de jardin. Vous pouvez utiliser, par exemple, du marbre, du basalte, du granit, du calcaire, du gneiss ou encore du gr\u00e8s. Ce dernier n\u00e9cessite un entretien et n&#8217;est pas aussi r\u00e9sistant \u00e0 la salet\u00e9 que les autres types. Beaucoup de gens d\u00e9cident \u00e9galement de construire un barbecue avec de la pierre des champs, que vous pouvez r\u00e9cup\u00e9rer vous-m\u00eame, mais cela prend beaucoup de temps. Les avantages d&#8217;un barbecue en pierre incluent sans aucun doute la durabilit\u00e9, mais aussi une apparence unique. Le mat\u00e9riau est souvent irr\u00e9gulier, ce qui offre de nombreuses possibilit\u00e9s de cr\u00e9er un design attractif.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"4-barbecue-avec-fumoir\">Barbecue avec fumoir<\/h3>\n\n\n\n<p>Souvent, la conception d&#8217;un barbecue, inclue l\u2019ajout des \u00e9l\u00e9ments pratiques. Ce sont g\u00e9n\u00e9ralement des \u00e9tag\u00e8res suppl\u00e9mentaires pour <a href=\"https:\/\/www.expondo.fr\/inspirations\/les-meilleurs-accessoires-pour-barbecue\/\" target=\"_blank\" rel=\"noreferrer noopener\">les meilleurs accessoires de barbecue<\/a> ou des plats cuisin\u00e9s. Il y a aussi ceux qui r\u00eavent de charcuteries maisons, alors ils cr\u00e9ent en plus un projet de fumoir de jardin. Vous pouvez en savoir plus sur la fa\u00e7on de construire un barbecue avec un <a href=\"https:\/\/www.expondo.fr\/royal-catering-fumoir-4-grilles-70-l-10010731\/\" target=\"_blank\" rel=\"noreferrer noopener\">fumoir<\/a> plus loin dans l&#8217;article.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"5-fabriquer-son-barbecue-pas-%C3%A0-pas\">Fabriquer son barbecue pas-\u00e0-pas<\/h2>\n\n\n\n<p>Une fois que vous savez avec quoi vous pouvez construire votre barbecue, vous \u00eates pr\u00eat \u00e0 vous mettre au travail. Tout d&#8217;abord, rassemblez les mat\u00e9riaux et les outils les plus n\u00e9cessaires. De quoi vous aurez besoin&nbsp;?<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"6-%C3%A9quipement-indispensable-pour-faire-son-barbecue-de-jardin-soi-m%C3%AAme\">\u00c9quipement indispensable pour faire son barbecue de jardin soi-m\u00eame<\/h3>\n\n\n\n<p>Vous devez absolument disposer du mat\u00e9riau de construction principal sous forme de briques, de clinker ou de pierre. Pour construire un barbecue, vous aurez \u00e9galement besoin d&#8217;un mortier sp\u00e9cialis\u00e9. Sur le march\u00e9, vous trouverez des mortiers ignifuges d\u00e9di\u00e9s aux barbecues en pierre et en brique. Vous avez \u00e9galement besoin de barres plates ou de canaux en m\u00e9tal qui serviront de renfort. Gr\u00e2ce \u00e0 eux, la structure gagnera en durabilit\u00e9.<\/p>\n\n\n\n<p>Si vous envisagez de construire un barbecue dans votre jardin et non sur votre terrasse, vous aurez besoin d&#8217;une fondation. Pour la pr\u00e9parer, vous avez besoin de beaucoup de gravier et de b\u00e9ton pour le coulage. Nous d\u00e9crirons la m\u00e9thode de cr\u00e9ation de la base du barbecue plus loin dans l&#8217;article.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"7-outils-de-construction-de-barbecue-de-jardin\">Outils de construction de barbecue de jardin<\/h3>\n\n\n\n<p>Comme vous allez construire une structure en briques dans votre jardin, <a href=\"https:\/\/www.expondo.fr\/engins-de-chantier\/\" target=\"_blank\" rel=\"noreferrer noopener\">les engins de chantier<\/a> professionnels s\u2019av\u00e9reront indispensables. Voici une courte liste d&#8217;appareils qui vous seront s\u00fbrement utiles :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>pilonneuse pour compacter le gravier sous la fondation,<\/li>\n\n\n\n<li>pelle ou petite excavatrice,<\/li>\n\n\n\n<li>guillotine ou meuleuse d&#8217;angle pour couper les briques en plus petits morceaux,<\/li>\n\n\n\n<li>malaxeur \u00e0 mortier ou perceuse avec malaxeur,<\/li>\n\n\n\n<li>truelle pour la pose du mortier,<\/li>\n\n\n\n<li>marteau de ma\u00e7onnerie,<\/li>\n\n\n\n<li>niveau \u00e0 bulle.<\/li>\n<\/ul>\n\n\n              <div id=\"expondo-products-block_5ad7f14e0b2b7b762e55d3f9fc455eb1\" class=\"expondo-block expondo-block--products\">\n          <div class=\"expondo-block__inner-container\">\n            <ul class=\"list list--products\">\n                              <li class=\"item\">\n                  <a href=\"\/msw-decoupeuse-thermique-2-500-w-10061041\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10061041_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/msw-decoupeuse-thermique-2-500-w-10061041\">\n                        D\u00e9coupeuse thermique &#8211; 2 500 W                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                              <ins>296.00&nbsp;\u20ac<\/ins>\n                    <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/msw-coupe-fer-a-beton-electrohydraulique-1-200-w-4-a-20-mm-10062742\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10062742_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/msw-coupe-fer-a-beton-electrohydraulique-1-200-w-4-a-20-mm-10062742\">\n                        Coupe fer \u00e0 b\u00e9ton &#8211; \u00e9lectrohydraulique &#8211; 1\u00a0200\u00a0W &#8211; 4 \u00e0 20\u00a0mm                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/steinberg-systems-leve-palette-1-500-kg-10030730\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10030730_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/steinberg-systems-leve-palette-1-500-kg-10030730\">\n                        L\u00e8ve-palette &#8211; 1\u00a0500\u00a0kg                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/msw-betonniere-63-l-avec-moteur-220-w-10062338\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10062338_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/msw-betonniere-63-l-avec-moteur-220-w-10062338\">\n                        B\u00e9tonni\u00e8re &#8211; 63 L &#8211; avec moteur &#8211; 220 W                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                          <\/ul>\n          <\/div>\n        <\/div>\n        \n\n\n<p>Selon vos besoins, cette liste peut \u00eatre un peu plus longue. Par exemple, il vaut la peine de se procurer des plinthes pour faciliter la pose uniforme de briques et de mortiers, ainsi que des ficelles et des chevilles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"8-comment-faire-un-barbecue-%C3%A9tape-1-%E2%80%93-projet\">Comment faire un barbecue ? \u00c9tape 1 \u2013 projet<\/h3>\n\n\n\n<p>Tout d&#8217;abord, vous avez besoin d&#8217;un projet dans lequel vous allez inclure les informations les plus importantes. Sur sa base, vous pourrez commencer \u00e0 construire un barbecue. La conception doit inclure des dimensions qui d\u00e9terminent la taille de l&#8217;espace que le b\u00e2timent occupera dans le jardin. Vous ne pouvez pas non plus oublier l&#8217;emplacement id\u00e9al. Il est pr\u00e9f\u00e9rable de le placer relativement pr\u00e8s du gazebo\/terrasse, mais suffisamment loin pour que la fum\u00e9e ne g\u00e2che pas la d\u00e9tente au grand air. Faites \u00e9galement attention aux voisins qui peuvent \u00eatre d\u00e9rang\u00e9s par les odeurs. Mieux vaut donc ne pas pr\u00e9voir de barbecue juste \u00e0 c\u00f4t\u00e9 de la cl\u00f4ture, \u00e0 moins que les voisins ne soient vos invit\u00e9s habituels. Dans ce cas, pensez \u00e0 poser votre portillon de jardin entre vos parcelles.<\/p>\n\n\n\n<p>\u00c0 ce stade, vous devez \u00e9galement prendre en compte tous les \u00e9l\u00e9ments suppl\u00e9mentaires du barbecue, tels que les \u00e9tag\u00e8res, le fumoir ou la hotte. Sinon, la s\u00e9lection des mat\u00e9riaux et outils n\u00e9cessaires sera tr\u00e8s difficile.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"9-comment-construire-un-barbecue-%C3%A9tape-2-%E2%80%93-fondations\">Comment construire un barbecue ? \u00c9tape 2 \u2013 fondations<\/h3>\n\n\n\n<p>Une fois que vous savez o\u00f9 vous allez construire votre barbecue, vous pouvez installer les fondations. Cela emp\u00eachera toute la structure de s&#8217;installer dans le sol. Tout d&#8217;abord, mesurez et marquez soigneusement l&#8217;endroit dans le jardin. Utilisez des chevilles et des ficelles pour cela. La profondeur de la fosse d\u00e9pend de la duret\u00e9 du sol. S&#8217;il est assez mou, cela vaut la peine de creuser une fondation plus profonde. Versez le gravier et compactez-le soigneusement en v\u00e9rifiant son niveau \u00e0 tout moment. Vous pouvez maintenant couler du b\u00e9ton. Aplanissez sa surface avec une truelle. Laissez les fondations se lier pendant au moins deux semaines. Par temps chaud, il vaut la peine de verser de l&#8217;eau dessus de temps en temps. De cette fa\u00e7on, vous r\u00e9duirez le risque de fissuration du b\u00e9ton. Apr\u00e8s avoir s\u00e9ch\u00e9 et nettoy\u00e9 la surface de la fondation, vous pouvez d\u00e9finir le contour de la grille en brique\/pierre.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"10-comment-faire-son-barbecue-%C3%A9tape-3-%E2%80%93-ma%C3%A7onnerie\">Comment faire son barbecue ? \u00c9tape 3 \u2013 ma\u00e7onnerie<\/h3>\n\n\n\n<p>Pr\u00e9parez le mortier selon les instructions du fabricant. Utilisez un agitateur \u00e9lectrique pour bien m\u00e9langer avec de l&#8217;eau. Placez la masse finie sur la plaque de fondation \u00e0 l&#8217;endroit o\u00f9 vous d\u00e9finissez le contour du gril et placez-y la premi\u00e8re couche de briques ou de pierres. Si vous utilisez des plinthes, placez-les entre les briques \u00e0 la fois verticalement et horizontalement. Apr\u00e8s avoir pos\u00e9 chaque couche, utilisez un niveau \u00e0 bulle pour v\u00e9rifier qu&#8217;elles sont uniformes. N&#8217;oubliez pas non plus de contr\u00f4ler les murs et les coins. Si n\u00e9cessaire, utilisez un marteau \u00e0 ma\u00e7onnerie pour \u00e9liminer les irr\u00e9gularit\u00e9s.<\/p>\n\n\n\n<p>Pour r\u00e9aliser un foyer, utilisez des fers plats en m\u00e9tal peints avec de la peinture anti-corrosion. Sur la derni\u00e8re couche de briques, posez le mortier et les fers plats. Ensuite, mettez une autre couche de mat\u00e9riau de construction par-dessus. Afin de maintenir le niveau et d&#8217;\u00e9viter la d\u00e9formation du m\u00e9tal, placez un support temporaire sous le foyer, par exemple compos\u00e9 de planches et d&#8217;un panneau de bois. La hauteur du foyer d\u00e9pend de vos pr\u00e9f\u00e9rences. On suppose qu&#8217;elle doit \u00eatre \u00e0 60-70 cm au-dessus du sol. Cependant, rien ne vous emp\u00eache de la construire un peu plus haut ou plus bas. Pour le cr\u00e9er, vous pouvez utiliser le composant principal du barbecue ou une t\u00f4le coulissante en acier r\u00e9sistant aux acides. Il est conseill\u00e9 de fabriquer le foyer de barbecue avec des trous ou des espaces entre les briques et de construire un tiroir \u00e0 cendres en dessous. De cette fa\u00e7on, vous am\u00e9liorerez le nettoyage du barbecue.<\/p>\n\n\n\n<p>Ce projet vous permet de cr\u00e9er un barbecue ouvert avec un design tr\u00e8s simple. Cependant, les personnes plus ambitieuses peuvent continuer et construire une hotte, obtenant ainsi une structure ferm\u00e9e. Pourquoi le r\u00e9aliser ? Tout d&#8217;abord : le toit prot\u00e8ge le barbecue contre les pr\u00e9cipitations, ce qui prolonge sa dur\u00e9e de vie, et permet \u00e9galement de l\u2019utiliser dans toutes les conditions. Deuxi\u00e8mement, cette construction r\u00e9duit la propagation de la fum\u00e9e \u00e0 chaque rafale de vent. On appr\u00e9ciera certainement respirer l&#8217;air frais plus que l&#8217;odeur suffocante de la fum\u00e9e. En plus de la hotte, vous pouvez \u00e9galement cr\u00e9er de l&#8217;espace pour des \u00e9tag\u00e8res en bois ou en verre tremp\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"11-de-quoi-dautre-il-vaut-penser-en-construisant-son-barbecue-\">De quoi d&#8217;autre il vaut penser en construisant son barbecue ?<\/h2>\n\n\n\n<p>Quelle que soit la variante que vous choisissez, il reste encore quelques \u00e9tapes \u00e0 franchir. L&#8217;une d&#8217;elles consiste \u00e0 combler les espaces entre les briques ou les pierres avec du mortier. Une fois cela fait, vous pouvez nettoyer les murs. Il y a aussi le r\u00e9glage de la grille en acier inoxydable. Vous trouverez certainement des grils pr\u00eats \u00e0 l&#8217;emploi chez de nombreux d\u00e9taillants. Cependant, vous devez vous rappeler d&#8217;adapter le gril \u00e0 leur taille. Une alternative est de commander la grille sur mesure ou de la fabriquer vous-m\u00eame. Si vous \u00eates familiaris\u00e9 avec le soudage des m\u00e9taux, vous pouvez utiliser diff\u00e9rents types de poste \u00e0 souder \u00e0 cette fin.<\/p>\n\n\n\n<p>Une fois le travail termin\u00e9, il est recommand\u00e9 de ne pas utiliser le barbecue pendant au moins deux semaines. Gr\u00e2ce \u00e0 cela, le mortier aura le temps de tout lier. Essayez d&#8217;allumer un petit feu la premi\u00e8re fois pour temp\u00e9rer le tout.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"12-comment-construire-un-barbecue-avec-fumoir-\">Comment construire un barbecue avec fumoir ?<\/h2>\n\n\n\n<p>Construire un barbecue avec un fumoir n&#8217;est pas si diff\u00e9rent de construire un barbecue tout simple. N\u00e9anmoins, il y a des points que vous devez garder \u00e0 l&#8217;esprit. Tout d&#8217;abord, construisez un fumoir avec le m\u00eame mat\u00e9riau que le barbecue. Gr\u00e2ce \u00e0 cela, vous conserverez la coh\u00e9rence esth\u00e9tique de la structure. Les fumoirs de jardin sont g\u00e9n\u00e9ralement construits sur un plan carr\u00e9 ou rectangulaire, et la forme ressemble \u00e0 une grande armoire.<\/p>\n\n\n\n<p>Un \u00e9l\u00e9ment important est le canal de fum\u00e9e reliant le four \u00e0 la chambre de fumage. Sa longueur affecte l&#8217;efficacit\u00e9 du processus de fumage. Un canal court est d\u00e9di\u00e9 \u00e0 la m\u00e9thode \u00e0 chaud et un long \u00e0 la m\u00e9thode \u00e0 froid. Id\u00e9alement, il devrait \u00eatre d&#8217;environ 1,5 m. La chemin\u00e9e joue \u00e9galement un r\u00f4le important. Elle \u00e9limine non seulement l&#8217;exc\u00e8s de fum\u00e9e, mais assure \u00e9galement un tirage ad\u00e9quat dans le fumoir. Il vaut la peine d&#8217;utiliser un amortisseur sp\u00e9cial pour r\u00e9guler la quantit\u00e9 de fum\u00e9e dans la chambre. \u00c0 l&#8217;int\u00e9rieur, il doit y avoir un endroit pour accrocher des b\u00e2tons et des crochets \u00e0 fumer. C&#8217;est une bonne pratique de les acheter avant de planifier la construction pour ajuster les dimensions de la chambre de fumage \u00e0 la longueur des b\u00e2tons.<\/p>\n\n\n              <div id=\"expondo-products-block_750c374c5e82c7af5ef9d232abc47143\" class=\"expondo-block expondo-block--products\">\n          <div class=\"expondo-block__inner-container\">\n            <ul class=\"list list--products\">\n                              <li class=\"item\">\n                  <a href=\"\/royal-catering-crochets-de-fumage-set-de-5-pieces-avec-crochets-griffes-18000288\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/18000288_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/royal-catering-crochets-de-fumage-set-de-5-pieces-avec-crochets-griffes-18000288\">\n                        Crochets de fumage set de 5 pi\u00e8ces &#8211; avec crochets-griffes                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/royal-catering-barbecue-au-charbon-de-bois-tablette-grille-rabattable-53-x-26-cm-inox-acier-royal-catering-10012965\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10012965_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/royal-catering-barbecue-au-charbon-de-bois-tablette-grille-rabattable-53-x-26-cm-inox-acier-royal-catering-10012965\">\n                        Barbecue au charbon de bois &#8211; tablette &#8211; rabattable- 53 x 26 cm &#8211; inox \/ acier &#8211; Royal Catering                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/royal-catering-barbecue-au-charbon-de-bois-avec-2-grilles-41-x-25-31-x-25-cm-inox-acier-galvanise-royal-catering-10012967\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10012967_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/royal-catering-barbecue-au-charbon-de-bois-avec-2-grilles-41-x-25-31-x-25-cm-inox-acier-galvanise-royal-catering-10012967\">\n                        Barbecue au charbon de bois &#8211; rabattable &#8211; avec 2 grilles &#8211; 41 x 25 \/ 31 x 25 cm &#8211; Inox, acier galvanis\u00e9 &#8211; Royal Catering                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/royal-catering-marmite-en-fonte-avec-couvercle-4-l-emaille-royal-catering-10013023\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10013023_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/royal-catering-marmite-en-fonte-avec-couvercle-4-l-emaille-royal-catering-10013023\">\n                        Marmite en fonte &#8211; avec couvercle &#8211; 4 L &#8211; \u00e9maill\u00e9 &#8211; Royal Catering                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                          <\/ul>\n          <\/div>\n        <\/div>\n        \n\n\n<h2 class=\"wp-block-heading\" id=\"13-la-fabrication-d%E2%80%99un-barbecue-de-jardin-n%E2%80%99est-pas-difficile\">La fabrication d\u2019un barbecue de jardin n\u2019est pas difficile<\/h2>\n\n\n\n<p>Faire son barbecue soi-m\u00eame est certainement quelque chose qui donnera beaucoup de satisfaction \u00e0 tout le monde. La mise en \u0153uvre de ce projet, depuis la s\u00e9lection des mat\u00e9riaux et outils appropri\u00e9s, en passant par la recherche d&#8217;un lieu, jusqu&#8217;\u00e0 la simple \u00e9rection du b\u00e2timent, est une t\u00e2che chronophage. Malgr\u00e9 cela, un barbecue en brique est sans aucun doute une d\u00e9coration parfaite pour tout jardin, pour lequel il vaut la peine de passer ce temps dessus.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En \u00e9t\u00e9, les barbecues sont un \u00e9l\u00e9ment indissociable de chaque jardin. De nombreuses personnes utilisent encore&hellip;<\/p>\n","protected":false},"author":11,"featured_media":10838,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_sb_is_suggestion_mode":false,"_sb_show_suggestion_boards":false,"_sb_show_comment_boards":false,"_sb_suggestion_history":"","_sb_update_block_changes":"","ub_ctt_via":"","rank_math_lock_modified_date":false,"_strive_post_notes":"","footnotes":""},"categories":[2849,2845],"tags":[],"promotion":[],"class_list":["post-11611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construction-et-bricolage","category-gastronomie-fr"],"acf":[],"featured_image_src":"https:\/\/www.expondo.fr\/inspirations\/wp-content\/uploads\/2021\/08\/construction-of-a-barbecue.jpg","author_info":{"display_name":"Maciej Skor\u017cepo","author_link":"https:\/\/www.expondo.fr\/inspirations\/author\/maciej-skorzepo\/"},"reading_time":"8","author_thumbnail":"https:\/\/secure.gravatar.com\/avatar\/3183c3d3fa9609213d6e58e2ecd78e08?s=96&d=mm&r=g","excerpt_full":"\n<p><strong>En \u00e9t\u00e9, les barbecues sont un \u00e9l\u00e9ment indissociable de chaque jardin. De nombreuses personnes utilisent encore des mod\u00e8les portables moins chers, mais les barbecues de jardin en briques fixes deviennent de plus en plus populaires. Ils permettent non seulement de pr\u00e9parer de d\u00e9licieux plats, mais ils constituent \u00e9galement une jolie d\u00e9coration de jardin. Dans cet article, vous apprendrez les conseils les plus importants qui vous seront utiles lors de la construction d'un barbecue.<\/strong><\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"0-construire-un-barbecue-types-de-barbecues-de-jardin\">Construire un barbecue - types de barbecues de jardin<\/h2>\n\n\n\n<p>Lorsque vous d\u00e9cidez de fabriquer un <a href=\"https:\/\/www.expondo.fr\/barbecue-professionnel\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/www.expondo.fr\/barbecue-professionnel\/\" rel=\"noreferrer noopener\">barbecue <\/a>de jardin, il convient de conna\u00eetre ses diff\u00e9rents types.\u00a0 Ils diff\u00e8rent principalement par le mat\u00e9riau de fabrication et les \u00e9l\u00e9ments suppl\u00e9mentaires que vous pouvez inclure dans sa conception.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"1-comment-construire-un-barbecue-en-brique-\">Comment construire un barbecue en brique ?<\/h3>\n\n\n\n<p>L'un des mat\u00e9riaux les plus populaires utilis\u00e9s dans la construction d'un barbecue est la brique. Sa forme r\u00e9guli\u00e8re rend la ma\u00e7onnerie plus confortable et la structure relativement commode \u00e0 traiter facilite la d\u00e9coupe de pi\u00e8ces plus petites quand n\u00e9cessaire. Lorsque vous choisissez les bonnes briques, faites attention non seulement \u00e0 c\u00f4t\u00e9 esth\u00e9tique, mais \u00e9galement \u00e0 leur r\u00e9sistance aux temp\u00e9ratures \u00e9lev\u00e9es. Ceci est particuli\u00e8rement important \u00e0 proximit\u00e9 du foyer et de la grille. Les briques de chamotte seront parfaites.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"2-barbecue-en-clinker\">Barbecue en clinker<\/h3>\n\n\n\n<p>Les briques de clinker sont \u00e9galement un mat\u00e9riau de construction tr\u00e8s durable. Elles sont fabriqu\u00e9es \u00e0 tr\u00e8s haute temp\u00e9rature, ce qui conf\u00e8re au produit fini une r\u00e9sistance extraordinaire. En cons\u00e9quence, elle devient r\u00e9sistante non seulement \u00e0 la chaleur ou au froid, mais aussi \u00e0 l'eau. Cela signifie qu'un barbecue en clinker peut r\u00e9sister aux conditions m\u00e9t\u00e9orologiques les plus s\u00e9v\u00e8res en \u00e9t\u00e9 comme en hiver. Un autre avantage est leur apparence attrayante. Sur le march\u00e9, vous trouverez des briques de diff\u00e9rentes couleurs, gr\u00e2ce auxquelles vous construirez un barbecue original.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"3-fabriquer-un-barbecue-en-pierre\">Fabriquer un barbecue en pierre<\/h3>\n\n\n\n<p>La pierre naturelle est un choix tr\u00e8s courant lorsqu'il s'agit de mat\u00e9riau pour un barbecue de jardin. Vous pouvez utiliser, par exemple, du marbre, du basalte, du granit, du calcaire, du gneiss ou encore du gr\u00e8s. Ce dernier n\u00e9cessite un entretien et n'est pas aussi r\u00e9sistant \u00e0 la salet\u00e9 que les autres types. Beaucoup de gens d\u00e9cident \u00e9galement de construire un barbecue avec de la pierre des champs, que vous pouvez r\u00e9cup\u00e9rer vous-m\u00eame, mais cela prend beaucoup de temps. Les avantages d'un barbecue en pierre incluent sans aucun doute la durabilit\u00e9, mais aussi une apparence unique. Le mat\u00e9riau est souvent irr\u00e9gulier, ce qui offre de nombreuses possibilit\u00e9s de cr\u00e9er un design attractif.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"4-barbecue-avec-fumoir\">Barbecue avec fumoir<\/h3>\n\n\n\n<p>Souvent, la conception d'un barbecue, inclue l\u2019ajout des \u00e9l\u00e9ments pratiques. Ce sont g\u00e9n\u00e9ralement des \u00e9tag\u00e8res suppl\u00e9mentaires pour <a href=\"https:\/\/www.expondo.fr\/inspirations\/les-meilleurs-accessoires-pour-barbecue\/\" target=\"_blank\" rel=\"noreferrer noopener\">les meilleurs accessoires de barbecue<\/a> ou des plats cuisin\u00e9s. Il y a aussi ceux qui r\u00eavent de charcuteries maisons, alors ils cr\u00e9ent en plus un projet de fumoir de jardin. Vous pouvez en savoir plus sur la fa\u00e7on de construire un barbecue avec un <a href=\"https:\/\/www.expondo.fr\/royal-catering-fumoir-4-grilles-70-l-10010731\/\" target=\"_blank\" rel=\"noreferrer noopener\">fumoir<\/a> plus loin dans l'article.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"5-fabriquer-son-barbecue-pas-%C3%A0-pas\">Fabriquer son barbecue pas-\u00e0-pas<\/h2>\n\n\n\n<p>Une fois que vous savez avec quoi vous pouvez construire votre barbecue, vous \u00eates pr\u00eat \u00e0 vous mettre au travail. Tout d'abord, rassemblez les mat\u00e9riaux et les outils les plus n\u00e9cessaires. De quoi vous aurez besoin&nbsp;?<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"6-%C3%A9quipement-indispensable-pour-faire-son-barbecue-de-jardin-soi-m%C3%AAme\">\u00c9quipement indispensable pour faire son barbecue de jardin soi-m\u00eame<\/h3>\n\n\n\n<p>Vous devez absolument disposer du mat\u00e9riau de construction principal sous forme de briques, de clinker ou de pierre. Pour construire un barbecue, vous aurez \u00e9galement besoin d'un mortier sp\u00e9cialis\u00e9. Sur le march\u00e9, vous trouverez des mortiers ignifuges d\u00e9di\u00e9s aux barbecues en pierre et en brique. Vous avez \u00e9galement besoin de barres plates ou de canaux en m\u00e9tal qui serviront de renfort. Gr\u00e2ce \u00e0 eux, la structure gagnera en durabilit\u00e9.<\/p>\n\n\n\n<p>Si vous envisagez de construire un barbecue dans votre jardin et non sur votre terrasse, vous aurez besoin d'une fondation. Pour la pr\u00e9parer, vous avez besoin de beaucoup de gravier et de b\u00e9ton pour le coulage. Nous d\u00e9crirons la m\u00e9thode de cr\u00e9ation de la base du barbecue plus loin dans l'article.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"7-outils-de-construction-de-barbecue-de-jardin\">Outils de construction de barbecue de jardin<\/h3>\n\n\n\n<p>Comme vous allez construire une structure en briques dans votre jardin, <a href=\"https:\/\/www.expondo.fr\/engins-de-chantier\/\" target=\"_blank\" rel=\"noreferrer noopener\">les engins de chantier<\/a> professionnels s\u2019av\u00e9reront indispensables. Voici une courte liste d'appareils qui vous seront s\u00fbrement utiles :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n\n\n\n\n\n\n\n\n\n\n\n<\/ul>\n\n\n\n\n\n<p>Selon vos besoins, cette liste peut \u00eatre un peu plus longue. Par exemple, il vaut la peine de se procurer des plinthes pour faciliter la pose uniforme de briques et de mortiers, ainsi que des ficelles et des chevilles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"8-comment-faire-un-barbecue-%C3%A9tape-1-%E2%80%93-projet\">Comment faire un barbecue ? \u00c9tape 1 \u2013 projet<\/h3>\n\n\n\n<p>Tout d'abord, vous avez besoin d'un projet dans lequel vous allez inclure les informations les plus importantes. Sur sa base, vous pourrez commencer \u00e0 construire un barbecue. La conception doit inclure des dimensions qui d\u00e9terminent la taille de l'espace que le b\u00e2timent occupera dans le jardin. Vous ne pouvez pas non plus oublier l'emplacement id\u00e9al. Il est pr\u00e9f\u00e9rable de le placer relativement pr\u00e8s du gazebo\/terrasse, mais suffisamment loin pour que la fum\u00e9e ne g\u00e2che pas la d\u00e9tente au grand air. Faites \u00e9galement attention aux voisins qui peuvent \u00eatre d\u00e9rang\u00e9s par les odeurs. Mieux vaut donc ne pas pr\u00e9voir de barbecue juste \u00e0 c\u00f4t\u00e9 de la cl\u00f4ture, \u00e0 moins que les voisins ne soient vos invit\u00e9s habituels. Dans ce cas, pensez \u00e0 poser votre portillon de jardin entre vos parcelles.<\/p>\n\n\n\n<p>\u00c0 ce stade, vous devez \u00e9galement prendre en compte tous les \u00e9l\u00e9ments suppl\u00e9mentaires du barbecue, tels que les \u00e9tag\u00e8res, le fumoir ou la hotte. Sinon, la s\u00e9lection des mat\u00e9riaux et outils n\u00e9cessaires sera tr\u00e8s difficile.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"9-comment-construire-un-barbecue-%C3%A9tape-2-%E2%80%93-fondations\">Comment construire un barbecue ? \u00c9tape 2 \u2013 fondations<\/h3>\n\n\n\n<p>Une fois que vous savez o\u00f9 vous allez construire votre barbecue, vous pouvez installer les fondations. Cela emp\u00eachera toute la structure de s'installer dans le sol. Tout d'abord, mesurez et marquez soigneusement l'endroit dans le jardin. Utilisez des chevilles et des ficelles pour cela. La profondeur de la fosse d\u00e9pend de la duret\u00e9 du sol. S'il est assez mou, cela vaut la peine de creuser une fondation plus profonde. Versez le gravier et compactez-le soigneusement en v\u00e9rifiant son niveau \u00e0 tout moment. Vous pouvez maintenant couler du b\u00e9ton. Aplanissez sa surface avec une truelle. Laissez les fondations se lier pendant au moins deux semaines. Par temps chaud, il vaut la peine de verser de l'eau dessus de temps en temps. De cette fa\u00e7on, vous r\u00e9duirez le risque de fissuration du b\u00e9ton. Apr\u00e8s avoir s\u00e9ch\u00e9 et nettoy\u00e9 la surface de la fondation, vous pouvez d\u00e9finir le contour de la grille en brique\/pierre.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"10-comment-faire-son-barbecue-%C3%A9tape-3-%E2%80%93-ma%C3%A7onnerie\">Comment faire son barbecue ? \u00c9tape 3 \u2013 ma\u00e7onnerie<\/h3>\n\n\n\n<p>Pr\u00e9parez le mortier selon les instructions du fabricant. Utilisez un agitateur \u00e9lectrique pour bien m\u00e9langer avec de l'eau. Placez la masse finie sur la plaque de fondation \u00e0 l'endroit o\u00f9 vous d\u00e9finissez le contour du gril et placez-y la premi\u00e8re couche de briques ou de pierres. Si vous utilisez des plinthes, placez-les entre les briques \u00e0 la fois verticalement et horizontalement. Apr\u00e8s avoir pos\u00e9 chaque couche, utilisez un niveau \u00e0 bulle pour v\u00e9rifier qu'elles sont uniformes. N'oubliez pas non plus de contr\u00f4ler les murs et les coins. Si n\u00e9cessaire, utilisez un marteau \u00e0 ma\u00e7onnerie pour \u00e9liminer les irr\u00e9gularit\u00e9s.<\/p>\n\n\n\n<p>Pour r\u00e9aliser un foyer, utilisez des fers plats en m\u00e9tal peints avec de la peinture anti-corrosion. Sur la derni\u00e8re couche de briques, posez le mortier et les fers plats. Ensuite, mettez une autre couche de mat\u00e9riau de construction par-dessus. Afin de maintenir le niveau et d'\u00e9viter la d\u00e9formation du m\u00e9tal, placez un support temporaire sous le foyer, par exemple compos\u00e9 de planches et d'un panneau de bois. La hauteur du foyer d\u00e9pend de vos pr\u00e9f\u00e9rences. On suppose qu'elle doit \u00eatre \u00e0 60-70 cm au-dessus du sol. Cependant, rien ne vous emp\u00eache de la construire un peu plus haut ou plus bas. Pour le cr\u00e9er, vous pouvez utiliser le composant principal du barbecue ou une t\u00f4le coulissante en acier r\u00e9sistant aux acides. Il est conseill\u00e9 de fabriquer le foyer de barbecue avec des trous ou des espaces entre les briques et de construire un tiroir \u00e0 cendres en dessous. De cette fa\u00e7on, vous am\u00e9liorerez le nettoyage du barbecue.<\/p>\n\n\n\n<p>Ce projet vous permet de cr\u00e9er un barbecue ouvert avec un design tr\u00e8s simple. Cependant, les personnes plus ambitieuses peuvent continuer et construire une hotte, obtenant ainsi une structure ferm\u00e9e. Pourquoi le r\u00e9aliser ? Tout d'abord : le toit prot\u00e8ge le barbecue contre les pr\u00e9cipitations, ce qui prolonge sa dur\u00e9e de vie, et permet \u00e9galement de l\u2019utiliser dans toutes les conditions. Deuxi\u00e8mement, cette construction r\u00e9duit la propagation de la fum\u00e9e \u00e0 chaque rafale de vent. On appr\u00e9ciera certainement respirer l'air frais plus que l'odeur suffocante de la fum\u00e9e. En plus de la hotte, vous pouvez \u00e9galement cr\u00e9er de l'espace pour des \u00e9tag\u00e8res en bois ou en verre tremp\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"11-de-quoi-dautre-il-vaut-penser-en-construisant-son-barbecue-\">De quoi d'autre il vaut penser en construisant son barbecue ?<\/h2>\n\n\n\n<p>Quelle que soit la variante que vous choisissez, il reste encore quelques \u00e9tapes \u00e0 franchir. L'une d'elles consiste \u00e0 combler les espaces entre les briques ou les pierres avec du mortier. Une fois cela fait, vous pouvez nettoyer les murs. Il y a aussi le r\u00e9glage de la grille en acier inoxydable. Vous trouverez certainement des grils pr\u00eats \u00e0 l'emploi chez de nombreux d\u00e9taillants. Cependant, vous devez vous rappeler d'adapter le gril \u00e0 leur taille. Une alternative est de commander la grille sur mesure ou de la fabriquer vous-m\u00eame. Si vous \u00eates familiaris\u00e9 avec le soudage des m\u00e9taux, vous pouvez utiliser diff\u00e9rents types de poste \u00e0 souder \u00e0 cette fin.<\/p>\n\n\n\n<p>Une fois le travail termin\u00e9, il est recommand\u00e9 de ne pas utiliser le barbecue pendant au moins deux semaines. Gr\u00e2ce \u00e0 cela, le mortier aura le temps de tout lier. Essayez d'allumer un petit feu la premi\u00e8re fois pour temp\u00e9rer le tout.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"12-comment-construire-un-barbecue-avec-fumoir-\">Comment construire un barbecue avec fumoir ?<\/h2>\n\n\n\n<p>Construire un barbecue avec un fumoir n'est pas si diff\u00e9rent de construire un barbecue tout simple. N\u00e9anmoins, il y a des points que vous devez garder \u00e0 l'esprit. Tout d'abord, construisez un fumoir avec le m\u00eame mat\u00e9riau que le barbecue. Gr\u00e2ce \u00e0 cela, vous conserverez la coh\u00e9rence esth\u00e9tique de la structure. Les fumoirs de jardin sont g\u00e9n\u00e9ralement construits sur un plan carr\u00e9 ou rectangulaire, et la forme ressemble \u00e0 une grande armoire.<\/p>\n\n\n\n<p>Un \u00e9l\u00e9ment important est le canal de fum\u00e9e reliant le four \u00e0 la chambre de fumage. Sa longueur affecte l'efficacit\u00e9 du processus de fumage. Un canal court est d\u00e9di\u00e9 \u00e0 la m\u00e9thode \u00e0 chaud et un long \u00e0 la m\u00e9thode \u00e0 froid. Id\u00e9alement, il devrait \u00eatre d'environ 1,5 m. La chemin\u00e9e joue \u00e9galement un r\u00f4le important. Elle \u00e9limine non seulement l'exc\u00e8s de fum\u00e9e, mais assure \u00e9galement un tirage ad\u00e9quat dans le fumoir. Il vaut la peine d'utiliser un amortisseur sp\u00e9cial pour r\u00e9guler la quantit\u00e9 de fum\u00e9e dans la chambre. \u00c0 l'int\u00e9rieur, il doit y avoir un endroit pour accrocher des b\u00e2tons et des crochets \u00e0 fumer. C'est une bonne pratique de les acheter avant de planifier la construction pour ajuster les dimensions de la chambre de fumage \u00e0 la longueur des b\u00e2tons.<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"13-la-fabrication-d%E2%80%99un-barbecue-de-jardin-n%E2%80%99est-pas-difficile\">La fabrication d\u2019un barbecue de jardin n\u2019est pas difficile<\/h2>\n\n\n\n<p>Faire son barbecue soi-m\u00eame est certainement quelque chose qui donnera beaucoup de satisfaction \u00e0 tout le monde. La mise en \u0153uvre de ce projet, depuis la s\u00e9lection des mat\u00e9riaux et outils appropri\u00e9s, en passant par la recherche d'un lieu, jusqu'\u00e0 la simple \u00e9rection du b\u00e2timent, est une t\u00e2che chronophage. Malgr\u00e9 cela, un barbecue en brique est sans aucun doute une d\u00e9coration parfaite pour tout jardin, pour lequel il vaut la peine de passer ce temps dessus.<\/p>\n\n\n\n<p><\/p>\n","_links":{"self":[{"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/posts\/11611"}],"collection":[{"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/comments?post=11611"}],"version-history":[{"count":9,"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/posts\/11611\/revisions"}],"predecessor-version":[{"id":90436,"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/posts\/11611\/revisions\/90436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/media\/10838"}],"wp:attachment":[{"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/media?parent=11611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/categories?post=11611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/tags?post=11611"},{"taxonomy":"promotion","embeddable":true,"href":"https:\/\/www.expondo.fr\/inspirations\/wp-json\/wp\/v2\/promotion?post=11611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}